{"id":92559,"date":"2018-06-06T09:48:54","date_gmt":"2018-06-06T12:48:54","guid":{"rendered":"http:\/\/portaldosilas.com.br\/?p=92559"},"modified":"2018-06-06T09:48:54","modified_gmt":"2018-06-06T12:48:54","slug":"em-fabriciano-carreta-atropela-e-mata-mulher","status":"publish","type":"post","link":"https:\/\/portaldosilas.com.br\/news\/2018\/06\/06\/em-fabriciano-carreta-atropela-e-mata-mulher\/","title":{"rendered":"Em Fabriciano: Carreta atropela e mata mulher"},"content":{"rendered":"<figure id=\"attachment_92560\" aria-describedby=\"caption-attachment-92560\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2018\/06\/ps.jpeg\"><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-92560 size-medium\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2018\/06\/ps-640x360.jpeg\" alt=\"\" width=\"640\" height=\"360\" \/><\/a><figcaption id=\"caption-attachment-92560\" class=\"wp-caption-text\">Plox<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Um\u00a0grave acidente ocorrido na noite dessa ter\u00e7a-feira (05) deixou uma pessoa morta em Coronel Fabriciano- MG.\u00a0Testemunhas relataram ao Plox que uma mulher, ainda n\u00e3o identificada teria tentado atravessar a via de rolamento da BR-381 , que corta a cidade quando foi atingida por uma carreta.<\/p>\n<p style=\"text-align: justify;\">O motorista do ve\u00edculo, de marca Sc\u00e2nia,\u00a0n\u00e3o foi identificado. Segundo informa\u00e7\u00f5es repassadas ao portal,\u00a0\u00a0a carreta\u00a0transportava combust\u00edveis a servi\u00e7o dos postos Petrobras.<\/p>\n<p style=\"text-align: justify;\">A mulher, que, conforme relatos de testemunhas, aparentava cinquenta e poucos anos ainda foi n\u00e3o identificada. Em conversa com a reportagem do Plox, os socorristas do Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia (SAMU) informaram\u00a0que\u00a0a Unidade de Servi\u00e7o de Atendimento (USA) se deslocou\u00a0para socorrer a v\u00edtima. &#8221; Fomos ao local, mas quando chegamos, constatamos o \u00f3bito&#8221;, afirmaram.<\/p>\n<p>Plox<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um\u00a0grave acidente ocorrido na noite dessa ter\u00e7a-feira (05) deixou uma pessoa morta em Coronel Fabriciano- MG.\u00a0Testemunhas relataram ao Plox que uma mulher, ainda n\u00e3o identificada teria tentado atravessar a via de rolamento da BR-381 , que corta a cidade quando foi atingida por uma carreta. O motorista do ve\u00edculo, de marca Sc\u00e2nia,\u00a0n\u00e3o foi identificado. Segundo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts\/92559"}],"collection":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/comments?post=92559"}],"version-history":[{"count":0,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts\/92559\/revisions"}],"wp:attachment":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/media?parent=92559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/categories?post=92559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/tags?post=92559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}