{"id":8876,"date":"2013-11-11T12:27:41","date_gmt":"2013-11-11T15:27:41","guid":{"rendered":"http:\/\/portaldosilas.com.br\/?p=8876"},"modified":"2013-11-11T12:27:41","modified_gmt":"2013-11-11T15:27:41","slug":"sepultado-em-ipatinga-o-corpo-do-irmao-joao-honorato","status":"publish","type":"post","link":"https:\/\/portaldosilas.com.br\/news\/2013\/11\/11\/sepultado-em-ipatinga-o-corpo-do-irmao-joao-honorato\/","title":{"rendered":"Sepultado, em Ipatinga, o corpo do irm\u00e3o Jo\u00e3o Honorato."},"content":{"rendered":"<figure id=\"attachment_8877\" aria-describedby=\"caption-attachment-8877\" style=\"width: 560px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-8877 \" alt=\"IMG_6061\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2013\/11\/IMG_6061-560x373.jpg\" width=\"560\" height=\"373\" \/><figcaption id=\"caption-attachment-8877\" class=\"wp-caption-text\"><span style=\"color: #000000;\"><em><strong>Jo\u00e3o Honorato, com o filho Cilas, no culto dos idosos do dia 24 de setembro passado, no templo sede, em Ipatinga.<\/strong><\/em><\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><em><strong>Num clima de muita consterna\u00e7\u00e3o, fi\u00e9is da Assembleia de Deus de Ipatinga, Minist\u00e9rio Pr. Ant\u00f4nio Rosa, \u00a0estiveram na manh\u00e3 desta segunda-feira, no templo da Rua Vi\u00e7osa, 54, centro, onde se despediram do corpo do irm\u00e3o Jo\u00e3o Honorato, um dos pioneiros da denomina\u00e7\u00e3o naquela cidade. V\u00edtima de insufici\u00eancia pulmonar, Jo\u00e3o Honorato faleceu, \u00a0aos 91 anos, \u00e0s 6h50 deste domingo, em um leito do hospital M\u00e1rcio Cunha, onde permaneceu internado durante 42 dias. Jo\u00e3o Honorato mantinha estreitos la\u00e7os de amizade com a fam\u00edlia do Pr. Ant\u00f4nio Rosa. Um dos seus filhos, Cilas Prado, h\u00e1 12 anos, \u00e9 motorista do presidente.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><em><strong>Jo\u00e3o, h\u00e1 51 anos, era membro da Assembleia de Deus e um dos seus legados foi a condu\u00e7\u00e3o dos seus filhos nos caminhos do Senhor. Seus exemplos de cidad\u00e3o e servo de Deus foram ressaltados exaustivamente durante a cerim\u00f4nia f\u00fanebre, presidida pelo Ev. Juvenil Machado e prestigiada por diversos pastores, dentre eles, Junior Calais, Jos\u00e9 Lopes, ambos de Coronel Fabriciano; Pr. Jacy Augusto,\u00a0 presb\u00edteros L\u00e1zaro, Pedro Braz e os evangelistas Argemiro e Valtemir.<\/strong><\/em><\/p>\n<figure id=\"attachment_8878\" aria-describedby=\"caption-attachment-8878\" style=\"width: 560px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-8878 \" alt=\"IMG_2964\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2013\/11\/IMG_2964-560x373.jpg\" width=\"560\" height=\"373\" srcset=\"https:\/\/portaldosilas.com.br\/news\/wp-content\/uploads\/2013\/11\/IMG_2964-560x373.jpg 560w, https:\/\/portaldosilas.com.br\/news\/wp-content\/uploads\/2013\/11\/IMG_2964.jpg 720w\" sizes=\"(max-width: 560px) 100vw, 560px\" \/><figcaption id=\"caption-attachment-8878\" class=\"wp-caption-text\"><span style=\"color: #000000;\"><em><strong>Ev. Juvenil Machado foi quem presidiu a cerim\u00f4nia f\u00fanebre.<\/strong><\/em><\/span><\/figcaption><\/figure>\n<figure id=\"attachment_8879\" aria-describedby=\"caption-attachment-8879\" style=\"width: 560px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-8879 \" alt=\"IMG_2962\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2013\/11\/IMG_2962-560x373.jpg\" width=\"560\" height=\"373\" srcset=\"https:\/\/portaldosilas.com.br\/news\/wp-content\/uploads\/2013\/11\/IMG_2962-560x373.jpg 560w, https:\/\/portaldosilas.com.br\/news\/wp-content\/uploads\/2013\/11\/IMG_2962.jpg 720w\" sizes=\"(max-width: 560px) 100vw, 560px\" \/><figcaption id=\"caption-attachment-8879\" class=\"wp-caption-text\"><span style=\"color: #000000;\"><em><strong>Pr. Eber falou em nome do presidente, Pr. Ant\u00f4nio Rosa e fam\u00edlia.<\/strong><\/em><\/span><\/figcaption><\/figure>\n<p style=\"text-align: center;\">\n<figure id=\"attachment_8880\" aria-describedby=\"caption-attachment-8880\" style=\"width: 560px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-8880 \" alt=\"IMG_2967\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2013\/11\/IMG_2967-560x373.jpg\" width=\"560\" height=\"373\" srcset=\"https:\/\/portaldosilas.com.br\/news\/wp-content\/uploads\/2013\/11\/IMG_2967-560x373.jpg 560w, https:\/\/portaldosilas.com.br\/news\/wp-content\/uploads\/2013\/11\/IMG_2967.jpg 720w\" sizes=\"(max-width: 560px) 100vw, 560px\" \/><figcaption id=\"caption-attachment-8880\" class=\"wp-caption-text\"><span style=\"color: #000000;\"><em><strong>Pr. Junior Calais, de Coronel Fabriciano<\/strong><\/em><\/span><\/figcaption><\/figure>\n<figure id=\"attachment_8881\" aria-describedby=\"caption-attachment-8881\" style=\"width: 560px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-8881 \" alt=\"IMG_2969\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2013\/11\/IMG_2969-560x373.jpg\" width=\"560\" height=\"373\" srcset=\"https:\/\/portaldosilas.com.br\/news\/wp-content\/uploads\/2013\/11\/IMG_2969-560x373.jpg 560w, https:\/\/portaldosilas.com.br\/news\/wp-content\/uploads\/2013\/11\/IMG_2969.jpg 720w\" sizes=\"(max-width: 560px) 100vw, 560px\" \/><figcaption id=\"caption-attachment-8881\" class=\"wp-caption-text\"><span style=\"color: #000000;\"><em><strong>Pb. L\u00e1zaro Bagliano<\/strong><\/em><\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><em><strong>Uma das virtudes destacadas do irm\u00e3o Jo\u00e3o Honorato foi sua capacidade de recitar, de cor, todos os textos \u00e1ureos das li\u00e7\u00f5es b\u00edblicas da escola dominical, do ano, na ordem e com suas respectivas cita\u00e7\u00f5es b\u00edblicas, o que evidencia seu apego e dedica\u00e7\u00e3o a este tipo de ensino, atividade onde, certamente, extra\u00eda subs\u00eddios para dar \u00e0 sua fam\u00edlia a estrutura que deu, item, dentre outros, que ir\u00e1 eternizar sua passagem por esta terra.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><em><strong>Convidado para falar em nome dos \u201cRosas\u201d, Pr. Eber Rosa frisou os exemplos de Honorato como um guerreiro. \u201cO legado deste guerreiro, exemplo intoc\u00e1vel, nestes 91 anos de vida, nos inspirar\u00e1 a todos\u201d, disse o assessor presidencial que fez coro com os que lembraram da atitude de Jo\u00e3o Honorato em recitar de cor os textos \u00e1ureos da li\u00e7\u00e3o b\u00edblica da escola dominical.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><em><strong>Em sua fala, em nome da fam\u00edlia, o Pb. Carlos Prado, um dos seis filhos vivos de Jo\u00e3o Honorato, destacou as caracter\u00edsticas do pai, respons\u00e1veis por sua reputa\u00e7\u00e3o como pai ideal. Carlos, bastante emocionado, lembrou de parte de suas conversas com seu genitor, em uma delas ouvindo dele que \u201cnunca esquecia os filhos em suas ora\u00e7\u00f5es\u201d. Jo\u00e3o Honorato era vi\u00favo, h\u00e1 5 anos, de Maria Isabel Prado.\u00a0 Al\u00e9m dos seis filhos vivos dos oito que teve, ele deixou 11 netos e 4 bisnetos.<\/strong><\/em><\/p>\n<figure id=\"attachment_8882\" aria-describedby=\"caption-attachment-8882\" style=\"width: 560px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-8882 \" alt=\"IMG_2972\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2013\/11\/IMG_2972-560x373.jpg\" width=\"560\" height=\"373\" srcset=\"https:\/\/portaldosilas.com.br\/news\/wp-content\/uploads\/2013\/11\/IMG_2972-560x373.jpg 560w, https:\/\/portaldosilas.com.br\/news\/wp-content\/uploads\/2013\/11\/IMG_2972.jpg 720w\" sizes=\"(max-width: 560px) 100vw, 560px\" \/><figcaption id=\"caption-attachment-8882\" class=\"wp-caption-text\"><span style=\"color: #000000;\"><em><strong>O filho, Pb. Carlos Prado, falou em nome da fam\u00edlia.<\/strong><\/em><\/span><\/figcaption><\/figure>\n<figure id=\"attachment_8883\" aria-describedby=\"caption-attachment-8883\" style=\"width: 560px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-8883 \" alt=\"IMG_2973\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2013\/11\/IMG_2973-560x373.jpg\" width=\"560\" height=\"373\" srcset=\"https:\/\/portaldosilas.com.br\/news\/wp-content\/uploads\/2013\/11\/IMG_2973-560x373.jpg 560w, https:\/\/portaldosilas.com.br\/news\/wp-content\/uploads\/2013\/11\/IMG_2973.jpg 720w\" sizes=\"(max-width: 560px) 100vw, 560px\" \/><figcaption id=\"caption-attachment-8883\" class=\"wp-caption-text\"><span style=\"color: #000000;\"><em><strong>Pr. Jos\u00e9 Lopes, de Coronel Fabriciano.<\/strong><\/em><\/span><\/figcaption><\/figure>\n<p style=\"text-align: center;\">\n<p style=\"text-align: center;\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-medium wp-image-8884\" alt=\"IMG_2975\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2013\/11\/IMG_2975-560x373.jpg\" width=\"560\" height=\"373\" srcset=\"https:\/\/portaldosilas.com.br\/news\/wp-content\/uploads\/2013\/11\/IMG_2975-560x373.jpg 560w, https:\/\/portaldosilas.com.br\/news\/wp-content\/uploads\/2013\/11\/IMG_2975.jpg 720w\" sizes=\"(max-width: 560px) 100vw, 560px\" \/><\/p>\n<figure id=\"attachment_8885\" aria-describedby=\"caption-attachment-8885\" style=\"width: 560px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-8885 \" alt=\"IMG_2976\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2013\/11\/IMG_2976-560x373.jpg\" width=\"560\" height=\"373\" srcset=\"https:\/\/portaldosilas.com.br\/news\/wp-content\/uploads\/2013\/11\/IMG_2976-560x373.jpg 560w, https:\/\/portaldosilas.com.br\/news\/wp-content\/uploads\/2013\/11\/IMG_2976.jpg 720w\" sizes=\"(max-width: 560px) 100vw, 560px\" \/><figcaption id=\"caption-attachment-8885\" class=\"wp-caption-text\"><span style=\"color: #000000;\"><em><strong>Pr. Jacy Augusto, no encerramento da cerim\u00f4nia.<\/strong><\/em><\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><em><strong>Por tudo que se ouviu a respeito do falecido era que se tratava de um homem probo, justo, reto e temente a Deus. Os \u201cPrados\u201d perderam um referencial de carinho, dedica\u00e7\u00e3o e ternura, para o c\u00e9u ganhar um servo que dedicou seus \u00faltimos 51 anos de vida como representante aut\u00eantico de quem preferiu a vida \u00e0 morte eterna. Jo\u00e3o Honorato, agora vive!<\/strong><\/em><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-8886 aligncenter\" alt=\"IMG_2978\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2013\/11\/IMG_2978-560x373.jpg\" width=\"560\" height=\"373\" srcset=\"https:\/\/portaldosilas.com.br\/news\/wp-content\/uploads\/2013\/11\/IMG_2978-560x373.jpg 560w, https:\/\/portaldosilas.com.br\/news\/wp-content\/uploads\/2013\/11\/IMG_2978.jpg 720w\" sizes=\"(max-width: 560px) 100vw, 560px\" \/><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-medium wp-image-8887\" alt=\"IMG_2983\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2013\/11\/IMG_2983-560x373.jpg\" width=\"560\" height=\"373\" srcset=\"https:\/\/portaldosilas.com.br\/news\/wp-content\/uploads\/2013\/11\/IMG_2983-560x373.jpg 560w, https:\/\/portaldosilas.com.br\/news\/wp-content\/uploads\/2013\/11\/IMG_2983.jpg 720w\" sizes=\"(max-width: 560px) 100vw, 560px\" \/><\/p>\n<p style=\"text-align: center;\">\n<p style=\"text-align: center;\">\n","protected":false},"excerpt":{"rendered":"<p>Num clima de muita consterna\u00e7\u00e3o, fi\u00e9is da Assembleia de Deus de Ipatinga, Minist\u00e9rio Pr. Ant\u00f4nio Rosa, \u00a0estiveram na manh\u00e3 desta segunda-feira, no templo da Rua Vi\u00e7osa, 54, centro, onde se despediram do corpo do irm\u00e3o Jo\u00e3o Honorato, um dos pioneiros da denomina\u00e7\u00e3o naquela cidade. V\u00edtima de insufici\u00eancia pulmonar, Jo\u00e3o Honorato faleceu, \u00a0aos 91 anos, \u00e0s [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts\/8876"}],"collection":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/comments?post=8876"}],"version-history":[{"count":0,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts\/8876\/revisions"}],"wp:attachment":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/media?parent=8876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/categories?post=8876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/tags?post=8876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}