{"id":77201,"date":"2017-02-02T10:24:08","date_gmt":"2017-02-02T13:24:08","guid":{"rendered":"http:\/\/portaldosilas.com.br\/?p=77201"},"modified":"2017-02-02T10:24:08","modified_gmt":"2017-02-02T13:24:08","slug":"oportunidades-de-aprendizado-instituto-do-inox-em-parceria-com-a-fundacao-aperam-acesita","status":"publish","type":"post","link":"https:\/\/portaldosilas.com.br\/news\/2017\/02\/02\/oportunidades-de-aprendizado-instituto-do-inox-em-parceria-com-a-fundacao-aperam-acesita\/","title":{"rendered":"Oportunidades de Aprendizado &#8211; Instituto do Inox, em parceria com a Funda\u00e7\u00e3o Aperam Acesita"},"content":{"rendered":"<figure id=\"attachment_77203\" aria-describedby=\"caption-attachment-77203\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2017\/02\/Instituto-do-Inox-Copy.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-77203 size-medium\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2017\/02\/Instituto-do-Inox-Copy-640x400.jpg\" width=\"640\" height=\"400\" \/><\/a><figcaption id=\"caption-attachment-77203\" class=\"wp-caption-text\">Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><em><strong>Instituto do Inox, em parceria com a Funda\u00e7\u00e3o Aperam Acesita, inicia o ano repleto de cursos e capacita\u00e7\u00f5es para a comunidade<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Se voc\u00ea come\u00e7ou o ano em busca de novas oportunidades, conhecimento ou ent\u00e3o pensando em empreender, o Instituto do Inox \u00e9 o local perfeito para voc\u00ea. Em parceria com a Funda\u00e7\u00e3o Aperam Acesita, o Instituto est\u00e1 oferecendo, apenas no primeiro trimestre de 2017, diversas capacita\u00e7\u00f5es e novidades, com dura\u00e7\u00e3o de curto, m\u00e9dio e longo prazo e o melhor: com pre\u00e7os acess\u00edveis a toda comunidade. As inscri\u00e7\u00f5es para o primeiro curso come\u00e7am na segunda-feira (06\/02). Por isso, fique atento \u00e0s datas e aos prazos!<\/p>\n<p style=\"text-align: justify;\">Para se inscrever, basta ir at\u00e9 o Instituto do Inox (Rua 38, 18A &#8211; Vila dos T\u00e9cnicos &#8211; Tim\u00f3teo\/MG) das 8h30 \u00e0s 11h30 e das 13h30 \u00e0s 17h e apresentar: 01 foto 3&#215;4, documento original de identidade, CPF, Cart\u00e3o SUS, comprovante de resid\u00eancia e de escolaridade. A inscri\u00e7\u00e3o s\u00f3 pode ser feita pelo pr\u00f3prio candidato que tamb\u00e9m deve ser maior de 18 anos. No site www.institutodoinox.com.br voc\u00ea confere a programa\u00e7\u00e3o completa e requisitos dos cursos. Mais informa\u00e7\u00f5es pelo telefone 31 3848 3967 ou pelo e-mail inox@institutodoinox.com.br.<\/p>\n<p style=\"text-align: justify;\">Cursos ofertados<\/p>\n<p style=\"text-align: justify;\"><strong>Curso Artesanato utilizando A\u00e7os Inoxid\u00e1veis<\/strong><\/p>\n<p style=\"text-align: justify;\">Duas turmas: manh\u00e3 e tarde<\/p>\n<p style=\"text-align: justify;\">Carga Hor\u00e1ria: 12 h<\/p>\n<p style=\"text-align: justify;\">Inscri\u00e7\u00f5es: 06 a 08\/02<\/p>\n<p style=\"text-align: justify;\">Taxa inscri\u00e7\u00e3o: R$10<\/p>\n<p style=\"text-align: justify;\">Valor do investimento: R$20 (\u00e0 vista dinheiro\/cart\u00e3o)<\/p>\n<p style=\"text-align: justify;\">Escolaridade: Ensino fundamental completo ou cursando<\/p>\n<p style=\"text-align: justify;\"><strong>Fabrica\u00e7\u00e3o de sistemas de ventila\u00e7\u00e3o para cozinhas profissionais, conforme NBR 14518<\/strong><\/p>\n<p style=\"text-align: justify;\">Carga Hor\u00e1ria: 40h<\/p>\n<p style=\"text-align: justify;\">Inscri\u00e7\u00f5es: 07 a 16\/02<\/p>\n<p style=\"text-align: justify;\">Valor do investimento: R$800 (at\u00e9 3x no cart\u00e3o)<\/p>\n<p style=\"text-align: justify;\">Escolaridade: Ensino M\u00e9dio completo ou cursando<\/p>\n<p style=\"text-align: justify;\">\u00c9 obrigat\u00f3rio conhecimento nos processos de soldagem TIG em a\u00e7o inoxid\u00e1vel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Instituto do Inox, em parceria com a Funda\u00e7\u00e3o Aperam Acesita, inicia o ano repleto de cursos e capacita\u00e7\u00f5es para a comunidade Se voc\u00ea come\u00e7ou o ano em busca de novas oportunidades, conhecimento ou ent\u00e3o pensando em empreender, o Instituto do Inox \u00e9 o local perfeito para voc\u00ea. Em parceria com a Funda\u00e7\u00e3o Aperam Acesita, o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts\/77201"}],"collection":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/comments?post=77201"}],"version-history":[{"count":0,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts\/77201\/revisions"}],"wp:attachment":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/media?parent=77201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/categories?post=77201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/tags?post=77201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}