{"id":74236,"date":"2016-12-12T11:48:04","date_gmt":"2016-12-12T14:48:04","guid":{"rendered":"http:\/\/portaldosilas.com.br\/?p=74236"},"modified":"2016-12-12T11:49:04","modified_gmt":"2016-12-12T14:49:04","slug":"em-ipatinga-o-dia-da-biblia-na-assembleia-de-deus-do-alto-iguacu","status":"publish","type":"post","link":"https:\/\/portaldosilas.com.br\/news\/2016\/12\/12\/em-ipatinga-o-dia-da-biblia-na-assembleia-de-deus-do-alto-iguacu\/","title":{"rendered":"Em Ipatinga: o Dia da B\u00edblia na Assembleia de Deus no Alto do Igua\u00e7u"},"content":{"rendered":"<figure style=\"width: 691px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" loading=\"lazy\" alt=\"\" src=\"https:\/\/scontent-gru2-1.xx.fbcdn.net\/v\/t1.0-9\/15350557_1595579940455957_2505495273271574151_n.jpg?oh=05fffe595ba0164f7af0b658b6be0859&amp;oe=58B2EF8D\" width=\"691\" height=\"390\" \/><figcaption class=\"wp-caption-text\">Facebook<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva;\"><strong>O Dia da B\u00edblia, segundo domingo de dezembro, data esquecida em muitas igrejas e minist\u00e9rios, foi comemorado com um desfile pelas principais rua do bairro Alto do Igua\u00e7u, em Ipatinga, na manh\u00e3 deste domingo.<\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Dia da B\u00edblia, segundo domingo de dezembro, data esquecida em muitas igrejas e minist\u00e9rios, foi comemorado com um desfile pelas principais rua do bairro Alto do Igua\u00e7u, em Ipatinga, na manh\u00e3 deste domingo.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts\/74236"}],"collection":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/comments?post=74236"}],"version-history":[{"count":0,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts\/74236\/revisions"}],"wp:attachment":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/media?parent=74236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/categories?post=74236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/tags?post=74236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}