{"id":74203,"date":"2016-12-12T07:49:03","date_gmt":"2016-12-12T10:49:03","guid":{"rendered":"http:\/\/portaldosilas.com.br\/?p=74203"},"modified":"2016-12-12T07:49:03","modified_gmt":"2016-12-12T10:49:03","slug":"de-timoteo-moto-roubada-em-timoteo-e-recuperada-em-pingo-dagua","status":"publish","type":"post","link":"https:\/\/portaldosilas.com.br\/news\/2016\/12\/12\/de-timoteo-moto-roubada-em-timoteo-e-recuperada-em-pingo-dagua\/","title":{"rendered":"De Tim\u00f3teo: Moto roubada em Tim\u00f3teo \u00e9 recuperada em Pingo D&#8217;\u00c1gua"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2016\/12\/237466_ext_arquivo.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-73675\" alt=\"237466_ext_arquivo\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2016\/12\/237466_ext_arquivo.jpg\" width=\"600\" height=\"300\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva;\"><strong>Por volta das 17h15 de ontem (11\/12), um ve\u00edculo roubado em Tim\u00f3teo foi localizado no Assentamento Chico Mendes, Zona Rural da cidade de Pingo D\u2019\u00c1gua. A Pol\u00edcia Militar recebeu a informa\u00e7\u00e3o de que estava havendo um movimento de pessoas suspeitas na estrada da zona rural que da sa\u00edda para Ipatinga. No local encontraram ca\u00edda\u00a0no canto da estrada a moto Yamaha YS 150 preta, placa PVV-..09 ca\u00edda no canto da estrada. O ve\u00edculo foi utilizado no roubo da lot\u00e9rica em Pingo D&#8217;\u00e1gua. Nenhum suspeito foi localizado. A motocicleta foi removida para o p\u00e1tio da Cidade de Caratinga.<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">Plant\u00e3o Policial<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por volta das 17h15 de ontem (11\/12), um ve\u00edculo roubado em Tim\u00f3teo foi localizado no Assentamento Chico Mendes, Zona Rural da cidade de Pingo D\u2019\u00c1gua. A Pol\u00edcia Militar recebeu a informa\u00e7\u00e3o de que estava havendo um movimento de pessoas suspeitas na estrada da zona rural que da sa\u00edda para Ipatinga. No local encontraram ca\u00edda\u00a0no canto [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts\/74203"}],"collection":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/comments?post=74203"}],"version-history":[{"count":0,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts\/74203\/revisions"}],"wp:attachment":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/media?parent=74203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/categories?post=74203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/tags?post=74203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}