{"id":60232,"date":"2016-04-04T11:03:21","date_gmt":"2016-04-04T14:03:21","guid":{"rendered":"http:\/\/portaldosilas.com.br\/?p=60232"},"modified":"2016-04-04T11:03:21","modified_gmt":"2016-04-04T14:03:21","slug":"homem-e-baleado-na-porta-de-bar-em-fabriciano","status":"publish","type":"post","link":"https:\/\/portaldosilas.com.br\/news\/2016\/04\/04\/homem-e-baleado-na-porta-de-bar-em-fabriciano\/","title":{"rendered":"Homem \u00e9 baleado na porta de Bar em Fabriciano"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2016\/03\/Sirene-Pol\u00edcia2.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-58540\" alt=\"Sirene-Pol\u00edcia\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2016\/03\/Sirene-Pol\u00edcia2.jpg\" width=\"500\" height=\"317\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong>Por volta das 20h29 de ontem (03\/04), a pol\u00edcia compareceu na avenida Magalh\u00e3es Pinto, 2776, Bairro Melo Viana. Foi v\u00edtima de tentativa de homic\u00eddio \u00a0Webert Gomes Moreira, 30 anos.Segundo ocorr\u00eancia Webert Gomes foi encontrado pela guarni\u00e7\u00e3o ca\u00eddo no ch\u00e3o do &#8220;David bar\u201d, e socorrido ao hospital S\u00e3o Camilo com perfura\u00e7\u00f5es na face e na perna esquerda. De acordo com testemunhas, a v\u00edtima estava no estabelecimento comercial sentado em uma cadeira, em companhia de outras pessoas, quando chegaram dois indiv\u00edduos de bicicleta um deles encapuzado , sacou uma arma de fogo e efetuou disparos contra Webert. Depois fugiram sentido ao bairro Santa Cruz. Uma pessoa passou a seguir os suspeitos e foi informando a localiza\u00e7\u00e3o deles aos policiais que fizeram a abordagem a Marcos Henrique Soares dos Santos, 18 anos, e Jos\u00e9 Roberto de Oliveira j\u00fanior ,19 anos. Ap\u00f3s serem detidos a testemunha an\u00f4nima fez novo contato com a PM confirmando serem eles foram conduzidos para \u00e0 Delegacia.<\/strong><\/p>\n<p style=\"text-align: justify;\">Plant\u00e3o Policial<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por volta das 20h29 de ontem (03\/04), a pol\u00edcia compareceu na avenida Magalh\u00e3es Pinto, 2776, Bairro Melo Viana. Foi v\u00edtima de tentativa de homic\u00eddio \u00a0Webert Gomes Moreira, 30 anos.Segundo ocorr\u00eancia Webert Gomes foi encontrado pela guarni\u00e7\u00e3o ca\u00eddo no ch\u00e3o do &#8220;David bar\u201d, e socorrido ao hospital S\u00e3o Camilo com perfura\u00e7\u00f5es na face e na perna [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts\/60232"}],"collection":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/comments?post=60232"}],"version-history":[{"count":0,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts\/60232\/revisions"}],"wp:attachment":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/media?parent=60232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/categories?post=60232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/tags?post=60232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}