{"id":57927,"date":"2016-03-03T01:21:19","date_gmt":"2016-03-03T04:21:19","guid":{"rendered":"http:\/\/portaldosilas.com.br\/?p=57927"},"modified":"2016-03-03T01:21:19","modified_gmt":"2016-03-03T04:21:19","slug":"em-timoteo-nilza-reis-lanca-seu-2o-cd","status":"publish","type":"post","link":"https:\/\/portaldosilas.com.br\/news\/2016\/03\/03\/em-timoteo-nilza-reis-lanca-seu-2o-cd\/","title":{"rendered":"Em Tim\u00f3teo: Nilza Reis lan\u00e7a seu 2\u00ba CD."},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2016\/03\/12512444_480110182180383_8942797073724428969_n.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-57928\" alt=\"12512444_480110182180383_8942797073724428969_n\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2016\/03\/12512444_480110182180383_8942797073724428969_n-640x471.jpg\" width=\"640\" height=\"471\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva;\"><strong>A cantora gospel Nilza Reis anunciou para o pr\u00f3ximo dia 20 de mar\u00e7o, \u00e0s 19h, na Assembleia de Deus do bairro Ana Moura, o lan\u00e7amento do seu 2\u00ba CD, &#8220;Arrebatamento&#8221;.<\/strong><\/span><br \/>\n<span style=\"font-family: verdana, geneva;\"><strong>Fiel ao estilo que marcou o in\u00edcio de sua carreira, Nilza Reis ir\u00e1 agradecer a Deus pelo feito que ela atribui \u00e0 Sua miseric\u00f3rdia. <\/strong><\/span><br \/>\n<span style=\"font-family: verdana, geneva;\"><strong>A cantora enfrentou recentmente problemas de sa\u00fade que foram superados com a gra\u00e7a do Senhor Jesus. Por isto, e muito mais, Nilza \u00a0pretende fazer do lan\u00e7amento do seu \u00e1lbum um momento de enaltecimento da bondade de Deus e n\u00e3o de exibicionismo ou coisa que o valha.<\/strong><\/span><br \/>\n<span style=\"font-family: verdana, geneva;\"><strong>A carreira de Nilza se deslancha e um dos motivos para isto, sem d\u00favida, \u00e9 sua humildade e seriedade no exerc\u00edcio do seu minist\u00e9rio. Sua vida crist\u00e3 est\u00e1 pautada em tudo que aprendeu de sua m\u00e3e, uma mulher de vida exemplar, j\u00e1 falecida. O ensino que recebeu de sempre agradecer a Deus pelas b\u00ean\u00e7\u00e3os recebidas foi uma das motiva\u00e7\u00f5es para que Nilza Reis transformasse o lan\u00e7amento do seu CD em uma culto de gratid\u00e3o a Deus.<\/strong><\/span><br \/>\n<span style=\"font-family: verdana, geneva;\"><strong>&#8220;Arrebatamento&#8221; promete consolidar a caminhada da cantora e os frutos deste trabalho certamente aparecer\u00e3o em enlevos para a alma e b\u00e1lsamo para os cora\u00e7\u00f5es, al\u00e9m de uma alerta para um fato prestes a acontecer: o arrebatamento.<\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A cantora gospel Nilza Reis anunciou para o pr\u00f3ximo dia 20 de mar\u00e7o, \u00e0s 19h, na Assembleia de Deus do bairro Ana Moura, o lan\u00e7amento do seu 2\u00ba CD, &#8220;Arrebatamento&#8221;. Fiel ao estilo que marcou o in\u00edcio de sua carreira, Nilza Reis ir\u00e1 agradecer a Deus pelo feito que ela atribui \u00e0 Sua miseric\u00f3rdia. A [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts\/57927"}],"collection":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/comments?post=57927"}],"version-history":[{"count":0,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts\/57927\/revisions"}],"wp:attachment":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/media?parent=57927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/categories?post=57927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/tags?post=57927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}