{"id":55717,"date":"2016-02-02T13:41:54","date_gmt":"2016-02-02T16:41:54","guid":{"rendered":"http:\/\/portaldosilas.com.br\/?p=55717"},"modified":"2016-02-02T13:41:54","modified_gmt":"2016-02-02T16:41:54","slug":"em-timoteo-com-duras-criticas-ao-governo-keisson-vereador-admite-sua-pre-candidatura-a-prefeito-da-cidade","status":"publish","type":"post","link":"https:\/\/portaldosilas.com.br\/news\/2016\/02\/02\/em-timoteo-com-duras-criticas-ao-governo-keisson-vereador-admite-sua-pre-candidatura-a-prefeito-da-cidade\/","title":{"rendered":"Em Tim\u00f3teo: Com duras cr\u00edticas ao governo Keisson vereador admite sua pr\u00e9-candidatura a prefeito da cidade"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2016\/02\/DSC_3578.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-55718\" alt=\"DSC_3578\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2016\/02\/DSC_3578-640x360.jpg\" width=\"640\" height=\"360\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva;\"><strong>Na abertura dos trabalhos da C\u00e2mara Municipal referentes ao ano de 2016, o \u00faltimo da atual legislatura, o vereador Douglas Willkys (PSB) anunciou que est\u00e1 encerrando sua trajet\u00f3ria no Legislativo. Ele cumpre seu segundo mandato.<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva;\"><strong>Douglas, com cr\u00edticas contundentes \u00e0 atual Administra\u00e7\u00e3o, admitiu sua pr\u00e9-candidatura a prefeito nas elei\u00e7\u00f5es deste ano e se definiu como da verdade. Veja o v\u00eddeo.<\/strong><\/span><\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/clUsFqyE-Oc\" height=\"415\" width=\"580\" allowfullscreen=\"\" frameborder=\"0\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na abertura dos trabalhos da C\u00e2mara Municipal referentes ao ano de 2016, o \u00faltimo da atual legislatura, o vereador Douglas Willkys (PSB) anunciou que est\u00e1 encerrando sua trajet\u00f3ria no Legislativo. Ele cumpre seu segundo mandato. Douglas, com cr\u00edticas contundentes \u00e0 atual Administra\u00e7\u00e3o, admitiu sua pr\u00e9-candidatura a prefeito nas elei\u00e7\u00f5es deste ano e se definiu como [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts\/55717"}],"collection":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/comments?post=55717"}],"version-history":[{"count":0,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts\/55717\/revisions"}],"wp:attachment":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/media?parent=55717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/categories?post=55717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/tags?post=55717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}