{"id":48897,"date":"2015-11-11T08:25:32","date_gmt":"2015-11-11T11:25:32","guid":{"rendered":"http:\/\/portaldosilas.com.br\/?p=48897"},"modified":"2015-11-11T08:25:32","modified_gmt":"2015-11-11T11:25:32","slug":"governador-valadares-decreta-estado-de-calamidade-por-causa-de-poluicao-do-rio-doce","status":"publish","type":"post","link":"https:\/\/portaldosilas.com.br\/news\/2015\/11\/11\/governador-valadares-decreta-estado-de-calamidade-por-causa-de-poluicao-do-rio-doce\/","title":{"rendered":"Governador Valadares decreta estado de calamidade por causa de polui\u00e7\u00e3o do Rio Doce"},"content":{"rendered":"<figure id=\"attachment_48898\" aria-describedby=\"caption-attachment-48898\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2015\/11\/20151110203218809972i.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-48898\" alt=\"20151110203218809972i\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2015\/11\/20151110203218809972i-640x400.jpg\" width=\"640\" height=\"400\" \/><\/a><figcaption id=\"caption-attachment-48898\" class=\"wp-caption-text\">Lama deixou o Rio Doce na Regi\u00e3o de Governador Valadares com a cor avermelhada (foto: Gladyston Rodrigues\/EM\/D.A.Press)<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva;\">A Prefeitura de Governador Valadares decretou estado de calamidade p\u00fablica em raz\u00e3o do desabastecimento de \u00e1gua na cidade. A medida foi tomada por causa da passagem da lama origin\u00e1ria das represas que se romperam em Mariana, na Regi\u00e3o Central de Minas Gerais, e que est\u00e1 percorrendo o Rio Doce. A prefeitura da cidade elaborou um plano emergencial que foi enviado para os governos Federal e Estadual e para a Samarco, respons\u00e1vel pelas minas que cederam. O Minist\u00e9rio P\u00fablico de Minas Gerais (MPMG) entrou com uma a\u00e7\u00e3o civil p\u00fablica contra a mineradora para que ela arque com os custos das a\u00e7\u00f5es emergenciais que ser\u00e3o tomadas para assegurar o abastecimento no munic\u00edpio.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva;\">O plano de emerg\u00eancia criado pela prefeitura do munic\u00edpio solicitou caminh\u00f5es-pipa \u00e0 Samarco para suprir a necessidade da popula\u00e7\u00e3o. Nesta ter\u00e7a-feria, 21 caminh\u00f5es j\u00e1 come\u00e7aram a buscar \u00e1gua em munic\u00edpios vizinhos como Frei Inoc\u00eancio, Marilac e Vale do A\u00e7o. A princ\u00edpio, ir\u00e3o abastecer institui\u00e7\u00f5es de sa\u00fade, ensino e abrigos. O munic\u00edpio estuda, tamb\u00e9m, a possibilidade de utilizar \u00e1gua de po\u00e7os artesianos.\u00a0<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva;\">O Minist\u00e9rio P\u00fablico ajuizou a\u00e7\u00e3o civil p\u00fablica cobrando da Samarco, liminarmente, todos os custos estipulados pelo plano emergencial da prefeitura. As requisi\u00e7\u00f5es principais s\u00e3o 80 caminh\u00f5es-pipa, que totalizam 800 mil litros de \u00e1gua por dia, especialmente para hospitais e escolas, 80 mil litros de \u00f3leo diesel, 50 reservat\u00f3rios de 30 mil litros, um ve\u00edculo com tra\u00e7\u00e3o nas quatro rodas, um barco a motor, entre outros.\u00a0<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva;\">\u201cN\u00f3s vamos fazer um apelo para o Governo de Minas que nos ajude a equacionar o problema da \u00e1gua tratada e tamb\u00e9m nas exig\u00eancias com a empresa. Para n\u00f3s, quem \u00e9 respons\u00e1vel \u00e9 a Samarco. \u00c9 dela que temos que exigir os cuidados com Governador Valadares. Essa \u00e9 a maior trag\u00e9dia ambiental, ecol\u00f3gica, humana, social e econ\u00f4mica que n\u00f3s vamos sofrer na regi\u00e3o da bacia do Rio Doce. A gente n\u00e3o sabe qual ser\u00e1 o futuro\u201d, afirmou a prefeita Elisa Costa (PT).\u00a0<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva;\">Ainda n\u00e3o h\u00e1 previs\u00e3o para a normalidade da situa\u00e7\u00e3o. &#8220;N\u00f3s n\u00e3o temos horizonte, prazo para que esta situa\u00e7\u00e3o se resolva, porque o cen\u00e1rio muda dia a dia. Ainda tem muita lama no distrito de Baguari. Ontem (segunda-feira) de manh\u00e3 soltou partes dos rejeitos e s\u00f3 chegaram \u00e0 noite. Muito tempo, por esta raz\u00e3o, a gente n\u00e3o sabe ainda o tempo que vai durar para sair toda lama da hidrel\u00e9trica para sair aqui&#8221;, disse a prefeita.\u00a0<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva;\">A lama que desce pela calha do Rio Doce chegou em Governador Valadares causando danos ambientais, al\u00e9m de transtornos e preocupa\u00e7\u00e3o para os moradores. Peixes apareceram mortos ao longo do munic\u00edpio e comunidades ribeirinhas. As fam\u00edlias fizeram uma corrida pela \u00e1gua e lotaram as distribuidoras. Pelo menos cinco bairros j\u00e1 est\u00e3o totalmente sem \u00e1gua.\u00a0<\/span><\/p>\n<div>\n<figure><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter\" itemprop=\"image\" title=\"Gladyston Rodrigues\/EM\/D.A.Press\" alt=\"Gladyston Rodrigues\/EM\/D.A.Press\" src=\"http:\/\/imgsapp.em.com.br\/app\/noticia_127983242361\/2015\/11\/10\/706546\/20151110203410811104a.jpg\" width=\"750\" height=\"495\" \/><figcaption>Ao longo do rio, v\u00e1rios peixes foram encontrados mortos (foto: Gladyston Rodrigues\/EM\/D.A.Press)<\/figcaption><\/figure>\n<\/div>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva;\">O corte do abastecimento foi uma das medidas sugeridas pela Ag\u00eancia Nacional de \u00c1guas (ANA) para evitar a contamina\u00e7\u00e3o da popula\u00e7\u00e3o. An\u00e1lises feitas na \u00e1gua, mostram que a turbidez est\u00e1 muito acima do toler\u00e1vel. A medida para o tratamento \u00e9 de 1.000 uT. Por volta das 14h, o n\u00edvel estava em 80 mil uT. A concentra\u00e7\u00e3o do ferro, que o \u00edndice toler\u00e1vel \u00e9 de 0,03 mg, estava com 410 mg. O mangan\u00eas estava em 118 miligramas e o alum\u00ednio 64,5, ambos acima do toler\u00e1vel.<\/span><\/p>\n<p>Estado de Minas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Governador Valadares decretou estado de calamidade p\u00fablica em raz\u00e3o do desabastecimento de \u00e1gua na cidade. A medida foi tomada por causa da passagem da lama origin\u00e1ria das represas que se romperam em Mariana, na Regi\u00e3o Central de Minas Gerais, e que est\u00e1 percorrendo o Rio Doce. A prefeitura da cidade elaborou um [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts\/48897"}],"collection":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/comments?post=48897"}],"version-history":[{"count":0,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts\/48897\/revisions"}],"wp:attachment":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/media?parent=48897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/categories?post=48897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/tags?post=48897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}