{"id":43891,"date":"2015-09-09T01:03:58","date_gmt":"2015-09-09T04:03:58","guid":{"rendered":"http:\/\/portaldosilas.com.br\/?p=43891"},"modified":"2015-09-09T01:03:58","modified_gmt":"2015-09-09T04:03:58","slug":"timoteo-duelo-de-mcs-atrai-jovens-para-a-praca-do-olaria","status":"publish","type":"post","link":"https:\/\/portaldosilas.com.br\/news\/2015\/09\/09\/timoteo-duelo-de-mcs-atrai-jovens-para-a-praca-do-olaria\/","title":{"rendered":"Tim\u00f3teo: Duelo de MCs atrai jovens para a pra\u00e7a do Olaria"},"content":{"rendered":"<figure id=\"attachment_43892\" aria-describedby=\"caption-attachment-43892\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2015\/09\/IMG_2788.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-43892\" alt=\"IMG_2788\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2015\/09\/IMG_2788-640x426.jpg\" width=\"640\" height=\"426\" \/><\/a><figcaption id=\"caption-attachment-43892\" class=\"wp-caption-text\">Mc Leozinho<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva;\"><strong>Um n\u00famero expressivo de jovens esteve na pra\u00e7a do bairro Olaria, na noite desta ter\u00e7a-feira (8), onde participou de mais uma edi\u00e7\u00e3o do projeto \u201cCultura na Pra\u00e7a\u201d, que tem seu ponto alto no duelo \u00a0de MCs.<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffcc00;\"><strong>Veja o v\u00eddeo da edi\u00e7\u00e3o do dia 4 de setembro<\/strong><\/span><\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/CxBKeFm5_Yo\" height=\"415\" width=\"580\" allowfullscreen=\"\" frameborder=\"0\"><\/iframe><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva;\"><strong>Organizado por Aldo Junior, a iniciativa vem chamando a aten\u00e7\u00e3o da juventude de Tim\u00f3teo, cuja participa\u00e7\u00e3o nos encontros, sempre em pra\u00e7as p\u00fablicas, \u00e9 cada vez maior.<\/strong><\/span><\/p>\n<figure id=\"attachment_43893\" aria-describedby=\"caption-attachment-43893\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2015\/09\/IMG_2768.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-43893\" alt=\"IMG_2768\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2015\/09\/IMG_2768-640x426.jpg\" width=\"640\" height=\"426\" \/><\/a><figcaption id=\"caption-attachment-43893\" class=\"wp-caption-text\">Aldo Junior, um dos l\u00edderes do projeto<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva;\"><strong>S\u00e3o escolhidos dois participantes de cada vez, os quais disputam, entre si, quem melhor improvisa em rap. A criatividade corre solta nesta hora e verdadeiros poetas se revelam em letras que interpretam sentimentos e anseios dos seus autores.<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva;\"><strong>Aldo Junior vem batalhando patroc\u00ednio para a ideia e, at\u00e9 agora, vem recebendo alguns que t\u00eam sido empregados, por exemplo, no aluguel de som. O projeto tem despertado interesse em algumas pessoas que o v\u00eam como uma forma de ocupa\u00e7\u00e3o e de express\u00e3o art\u00edstica dos jovens da cidade.<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva;\"><strong>O \u201cCultura na Pra\u00e7a\u201d, de acordo com Aldo Junior, acontece nas ter\u00e7as-feiras, com exce\u00e7\u00e3o da pr\u00f3xima.\u00a0<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2015\/09\/IMG_2770.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-43894\" alt=\"IMG_2770\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2015\/09\/IMG_2770-640x426.jpg\" width=\"640\" height=\"426\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2015\/09\/IMG_2833.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-43895\" alt=\"IMG_2833\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2015\/09\/IMG_2833-640x426.jpg\" width=\"640\" height=\"426\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2015\/09\/IMG_2839.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-43896\" alt=\"IMG_2839\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2015\/09\/IMG_2839-640x426.jpg\" width=\"640\" height=\"426\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2015\/09\/IMG_2851.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-43897\" alt=\"IMG_2851\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2015\/09\/IMG_2851-640x426.jpg\" width=\"640\" height=\"426\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2015\/09\/IMG_2884.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-43898\" alt=\"IMG_2884\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2015\/09\/IMG_2884-640x426.jpg\" width=\"640\" height=\"426\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2015\/09\/IMG_2896.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-43899\" alt=\"IMG_2896\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2015\/09\/IMG_2896-640x426.jpg\" width=\"640\" height=\"426\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um n\u00famero expressivo de jovens esteve na pra\u00e7a do bairro Olaria, na noite desta ter\u00e7a-feira (8), onde participou de mais uma edi\u00e7\u00e3o do projeto \u201cCultura na Pra\u00e7a\u201d, que tem seu ponto alto no duelo \u00a0de MCs. Veja o v\u00eddeo da edi\u00e7\u00e3o do dia 4 de setembro Organizado por Aldo Junior, a iniciativa vem chamando a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts\/43891"}],"collection":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/comments?post=43891"}],"version-history":[{"count":0,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts\/43891\/revisions"}],"wp:attachment":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/media?parent=43891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/categories?post=43891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/tags?post=43891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}