{"id":40488,"date":"2015-07-07T12:46:15","date_gmt":"2015-07-07T15:46:15","guid":{"rendered":"http:\/\/portaldosilas.com.br\/?p=40488"},"modified":"2015-07-07T12:46:15","modified_gmt":"2015-07-07T15:46:15","slug":"definido-horario-de-sepultamento-de-silvina-de-barros","status":"publish","type":"post","link":"https:\/\/portaldosilas.com.br\/news\/2015\/07\/07\/definido-horario-de-sepultamento-de-silvina-de-barros\/","title":{"rendered":"Definido hor\u00e1rio de sepultamento de Silvina de Barros"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2015\/07\/sivina-3.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-40478\" alt=\"sivina (3)\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2015\/07\/sivina-3.jpg\" width=\"227\" height=\"287\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-family: verdana, geneva;\">De acordo com informa\u00e7\u00e3o de um membro da fam\u00edlia, ser\u00e1 nesta quarta-feira, \u00e0s 10h, o sepultamento do corpo de Silvina de Barros, falecida na madrugada de hoje, em decorr\u00eancia de uma parada card\u00edaca. O vel\u00f3rio acontece no templo da Assembleia de Deus do bairro Olaria, em Tim\u00f3teo.<\/span><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De acordo com informa\u00e7\u00e3o de um membro da fam\u00edlia, ser\u00e1 nesta quarta-feira, \u00e0s 10h, o sepultamento do corpo de Silvina de Barros, falecida na madrugada de hoje, em decorr\u00eancia de uma parada card\u00edaca. O vel\u00f3rio acontece no templo da Assembleia de Deus do bairro Olaria, em Tim\u00f3teo.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts\/40488"}],"collection":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/comments?post=40488"}],"version-history":[{"count":0,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts\/40488\/revisions"}],"wp:attachment":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/media?parent=40488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/categories?post=40488"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/tags?post=40488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}