{"id":36854,"date":"2015-05-05T10:50:08","date_gmt":"2015-05-05T13:50:08","guid":{"rendered":"http:\/\/portaldosilas.com.br\/?p=36854"},"modified":"2015-05-05T10:50:08","modified_gmt":"2015-05-05T13:50:08","slug":"jovens-e-adolescentes-da-igreja-deus-e-amor-do-bairro-alegre-reapresentaram-peca-no-domingo","status":"publish","type":"post","link":"https:\/\/portaldosilas.com.br\/news\/2015\/05\/05\/jovens-e-adolescentes-da-igreja-deus-e-amor-do-bairro-alegre-reapresentaram-peca-no-domingo\/","title":{"rendered":"Jovens e adolescentes da Igreja Deus \u00e9 Amor, do bairro Alegre, reapresentaram pe\u00e7a no domingo"},"content":{"rendered":"<p><a href=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2015\/05\/21.png\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-36855\" alt=\"21\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2015\/05\/21-580x316.png\" width=\"580\" height=\"316\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-family: verdana, geneva;\">No domingo (3) final do Congresso, os jovens e adolescentes da Igreja Pentecostal Deus \u00e9 Amor, do bairro Alegre, em Tim\u00f3teo, reapresentaram uma pe\u00e7a teatral, cuja mensagem era uma advert\u00eancia \u00e0 igreja quanto aos perigos decorrentes da neglig\u00eancia espiritual. Diferentemente do s\u00e1bado, a pe\u00e7a teve inser\u00e7\u00e3o de novos atores e mudan\u00e7a de figurino. Assista ao v\u00eddeo.<\/span><\/strong><\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/UH_PgNioqdo\" height=\"415\" width=\"580\" allowfullscreen=\"\" frameborder=\"0\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; No domingo (3) final do Congresso, os jovens e adolescentes da Igreja Pentecostal Deus \u00e9 Amor, do bairro Alegre, em Tim\u00f3teo, reapresentaram uma pe\u00e7a teatral, cuja mensagem era uma advert\u00eancia \u00e0 igreja quanto aos perigos decorrentes da neglig\u00eancia espiritual. Diferentemente do s\u00e1bado, a pe\u00e7a teve inser\u00e7\u00e3o de novos atores e mudan\u00e7a de figurino. Assista [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts\/36854"}],"collection":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/comments?post=36854"}],"version-history":[{"count":0,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts\/36854\/revisions"}],"wp:attachment":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/media?parent=36854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/categories?post=36854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/tags?post=36854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}