{"id":34749,"date":"2015-04-04T00:26:08","date_gmt":"2015-04-04T03:26:08","guid":{"rendered":"http:\/\/portaldosilas.com.br\/?p=34749"},"modified":"2015-04-04T00:33:21","modified_gmt":"2015-04-04T03:33:21","slug":"pastor-e-deputado-hidekazu-takayama-esta-internado-em-estado-grave-por-problemas-cardiacos","status":"publish","type":"post","link":"https:\/\/portaldosilas.com.br\/news\/2015\/04\/04\/pastor-e-deputado-hidekazu-takayama-esta-internado-em-estado-grave-por-problemas-cardiacos\/","title":{"rendered":"Pastor e deputado Hidekazu Takayama est\u00e1 internado em estado grave por problemas card\u00edacos"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2015\/04\/Antonio-Izami-Takayama.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-34750\" alt=\"Antonio-Izami-Takayama\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2015\/04\/Antonio-Izami-Takayama-580x385.jpg\" width=\"580\" height=\"385\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">O pastor e deputado federal Hidekazu Takayama (PSC-PR) est\u00e1 internado em estado grave na Unidade de Terapia Intensiva (UTI) de um hospital em Curitiba (PR), devido a problemas card\u00edacos.<\/p>\n<p style=\"text-align: justify;\">A informa\u00e7\u00e3o foi divulgada no Facebook por Ulisses Camargo, assessor de imprensa da Assembleia de Deus em Curitiba.<\/p>\n<p style=\"text-align: justify;\">De acordo com a breve nota do assessor de imprensa, Takayama encontra-se em um delicado estado de sa\u00fade pois seu cora\u00e7\u00e3o estaria funcionando de maneira prec\u00e1ria, e para reverter o quadro seria necess\u00e1ria \u201cuma interven\u00e7\u00e3o divina\u201d.<\/p>\n<p style=\"text-align: justify;\">\u201cIntercessores, admiradores do minist\u00e9rio do pastor e deputado federal (PSC-PR) Hidekazu Takayama, convocamos cada um para juntarem-se a n\u00f3s em ora\u00e7\u00e3o, pela vida de nosso pastor que est\u00e1 na U.T.I. de um Hospital em Curitiba necessitando de um milagre, pois foi diagnosticado com funcionamento prec\u00e1rio do seu cora\u00e7\u00e3o. A situa\u00e7\u00e3o \u00e9 grave e requer uma interven\u00e7\u00e3o divina. Ele que tanto orou por n\u00f3s, agora precisa da f\u00e9 e da intercess\u00e3o, daqueles que acreditam que ainda o veremos na r\u00e1dio Gospel, nos p\u00falpitos, na pra\u00e7a, na carreta ou onde exista um povo sedento por uma palavra de f\u00e9. Ore, Divulgue e interceda. Deus haver\u00e1 de ouvir nosso clamor. Importante, ele n\u00e3o pode receber visitas\u201d, escreveu Camargo.<\/p>\n<p style=\"text-align: justify;\">O pastor Geremias do Couto tamb\u00e9m usou as redes sociais para comentar a interna\u00e7\u00e3o do pastor, que \u00e9 integrante da bancada evang\u00e9lica. Couto afirmou que teve uma conversa animada com Takayama dois dias antes em Bras\u00edlia (DF) e que foi pego de surpresa.<\/p>\n<p style=\"text-align: justify;\">\u201cAnteontem \u00e0 tarde estivemos com o pastor e deputado federal Hidekazu Takaiama, no plen\u00e1rio da C\u00e2mara dos Deputados, em animada conversa, onde nos lembramos de nossos bons tempos no IBAD e demos boas risadas. Agora h\u00e1 pouco fomos surpreendidos com a not\u00edcia de que ele se encontra internado no CTI de um hospital em Curitiba, em estado grave por causa do funcionamento prec\u00e1rio do cora\u00e7\u00e3o. Convido a todos para juntarem-se a n\u00f3s na brecha da intercess\u00e3o em favor do nosso irm\u00e3o em Cristo\u201d, disse Couto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O pastor e deputado federal Hidekazu Takayama (PSC-PR) est\u00e1 internado em estado grave na Unidade de Terapia Intensiva (UTI) de um hospital em Curitiba (PR), devido a problemas card\u00edacos. A informa\u00e7\u00e3o foi divulgada no Facebook por Ulisses Camargo, assessor de imprensa da Assembleia de Deus em Curitiba. De acordo com a breve nota do assessor [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts\/34749"}],"collection":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/comments?post=34749"}],"version-history":[{"count":0,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts\/34749\/revisions"}],"wp:attachment":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/media?parent=34749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/categories?post=34749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/tags?post=34749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}