{"id":22417,"date":"2014-08-08T10:29:00","date_gmt":"2014-08-08T13:29:00","guid":{"rendered":"http:\/\/portaldosilas.com.br\/?p=22417"},"modified":"2014-08-08T10:29:00","modified_gmt":"2014-08-08T13:29:00","slug":"comeca-o-congresso-da-assembleia-de-deus-do-bairro-macuco","status":"publish","type":"post","link":"https:\/\/portaldosilas.com.br\/news\/2014\/08\/08\/comeca-o-congresso-da-assembleia-de-deus-do-bairro-macuco\/","title":{"rendered":"Come\u00e7a o Congresso da Assembleia de Deus do bairro Macuco."},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2014\/08\/10524853_551337344992670_1109524479_n.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-22418 aligncenter\" alt=\"10524853_551337344992670_1109524479_n\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2014\/08\/10524853_551337344992670_1109524479_n-580x236.jpg\" width=\"580\" height=\"236\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Os jovens e adolescentes da Assembleia de Deus do bairro Macuco, em Tim\u00f3teo, \u201cGera\u00e7\u00e3o Eleita\u201d, d\u00e3o in\u00edcio logo mais, \u00e0s 18h30, a mais um congresso da classe, que se estender\u00e1 at\u00e9 o pr\u00f3ximo domingo, 10, Dia dos Pais.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Segundo um material publicit\u00e1rio elaborado para divulgar o evento, 41 grupos de jovens estar\u00e3o participando do evento, inclusive os da regional de Cachoeira do Vale, onde acontece, nos mesmos dias, um congresso de miss\u00f5es.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Os pregadores anunciados s\u00e3o os pastores Cl\u00e9ber Souza, do Esp\u00edrito Santo, e Marcos Junior, de Minas Gerais.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>N\u00e3o informa\u00e7\u00e3o de outras participa\u00e7\u00f5es nos louvores, al\u00e9m dos \u201c41\u201d grupos de jovens.<\/strong><\/p>\n<figure id=\"attachment_22419\" aria-describedby=\"caption-attachment-22419\" style=\"width: 580px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2014\/08\/10524853_551337344992670_1109524479_n-1.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-22419 \" alt=\"10524853_551337344992670_1109524479_n (1)\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2014\/08\/10524853_551337344992670_1109524479_n-1-580x94.jpg\" width=\"580\" height=\"94\" \/><\/a><figcaption id=\"caption-attachment-22419\" class=\"wp-caption-text\"><em><strong>Olha a rela\u00e7\u00e3o dos conjuntos que ter\u00e3o &#8220;participa\u00e7\u00e3o especial&#8221;.<\/strong><\/em><\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Os jovens e adolescentes da Assembleia de Deus do bairro Macuco, em Tim\u00f3teo, \u201cGera\u00e7\u00e3o Eleita\u201d, d\u00e3o in\u00edcio logo mais, \u00e0s 18h30, a mais um congresso da classe, que se estender\u00e1 at\u00e9 o pr\u00f3ximo domingo, 10, Dia dos Pais. Segundo um material publicit\u00e1rio elaborado para divulgar o evento, 41 grupos de jovens estar\u00e3o participando do evento, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts\/22417"}],"collection":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/comments?post=22417"}],"version-history":[{"count":0,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts\/22417\/revisions"}],"wp:attachment":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/media?parent=22417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/categories?post=22417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/tags?post=22417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}