{"id":19373,"date":"2014-06-06T08:53:01","date_gmt":"2014-06-06T11:53:01","guid":{"rendered":"http:\/\/portaldosilas.com.br\/?p=19373"},"modified":"2014-06-07T17:12:04","modified_gmt":"2014-06-07T20:12:04","slug":"sofro-de-injustica-relevante-injustica-que-a-mim-soa-como-covardia-disse-marcus-andre-na-tribuna-da-camara-municipal-de-timoteo-ouca-o-pronunciamento-dele-na-integra","status":"publish","type":"post","link":"https:\/\/portaldosilas.com.br\/news\/2014\/06\/06\/sofro-de-injustica-relevante-injustica-que-a-mim-soa-como-covardia-disse-marcus-andre-na-tribuna-da-camara-municipal-de-timoteo-ouca-o-pronunciamento-dele-na-integra\/","title":{"rendered":"\u201cSofro de injusti\u00e7a, relevante injusti\u00e7a, que a mim soa como covardia\u201d, disse Marcus Andr\u00e9 na tribuna da C\u00e2mara Municipal de Tim\u00f3teo. Ou\u00e7a o pronunciamento dele na \u00edntegra."},"content":{"rendered":"<figure id=\"attachment_19218\" aria-describedby=\"caption-attachment-19218\" style=\"width: 580px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2014\/06\/IMG_2809.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-19218 \" alt=\"IMG_2809\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2014\/06\/IMG_2809-580x386.jpg\" width=\"580\" height=\"386\" \/><\/a><figcaption id=\"caption-attachment-19218\" class=\"wp-caption-text\"><span style=\"color: #ffffff;\"><em><strong>Marcos Andr\u00e9 est\u00e1 lutando pelos direitos na C\u00e2mara Municipal de Tim\u00f3teo.<\/strong><\/em><\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><em><strong>Segundo o servidor a C\u00e2mara Municipal vem negando reconhecer seu curso de teologia para fins de progress\u00e3o.<\/strong><\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><strong>Marcus Andr\u00e9, funcion\u00e1rio concursado da C\u00e2mara Municipal de Tim\u00f3teo, ocupou a tribuna da casa na tarde desta segunda-feira(2) no expediente conhecido como Tribuna Livre, que faz parte da programa\u00e7\u00e3o das reuni\u00f5es ordin\u00e1rias do legislativo timotense.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Com uma excelente dic\u00e7\u00e3o, pausadamente e com certa dose de emo\u00e7\u00e3o, o funcion\u00e1rio, que \u00e9 evang\u00e9lico, queixou-se do tratamento que, segundo ele, soa a injusti\u00e7a. Marcus afirmou que em 2008, quando foi apresentado ao ent\u00e3o presidente da C\u00e2mara, \u00a0lhe fora dito que se preparasse \u201cporque um futuro promissor o aguardava\u201d. O servidor acreditou naquela promessa e come\u00e7ou a envidar esfor\u00e7os no sentido de qualificar-se. \u201cEntusiasmado, esforcei-me e terminei meus estudos de grau superior\u201d, disse Marcus, que reconheceu a generosidade da casa em ajudar-lhe a custear parte da p\u00f3s-gradua\u00e7\u00e3o. O ocupante da tribuna, por\u00e9m, registrou uma contradi\u00e7\u00e3o entre a ajuda e o tratamento que a institui\u00e7\u00e3o agora lhe dispensa. \u201cAgora, que estou mais capacitado, me nega o que todos, repito, o que todos os servidores habilitados nesta casa t\u00eam\u201d, reclamou Marcus, que\u00a0 \u00e9\u00a0 bacharel em teologia.<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2014\/06\/mqdefault-1.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-19374 alignleft\" alt=\"mqdefault (1)\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2014\/06\/mqdefault-1.jpg\" width=\"320\" height=\"180\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><strong>O servidor disse que em abril do ano passado protocolou junto ao departamento de recursos humanos da C\u00e2mara um pedido de progress\u00e3o por conhecimento, benef\u00edcio, segundo o evang\u00e9lico, conquistado por todos os outros servidores da casa. Marcus n\u00e3o conseguiu a progress\u00e3o nos graus pleiteados, sob a alega\u00e7\u00e3o de que seu curso \u2013 de teologia \u2013 n\u00e3o \u00e9 competente \u00e0 progress\u00e3o requerida, com posterior invalida\u00e7\u00e3o da p\u00f3s-gradua\u00e7\u00e3o do pleiteante. O funcion\u00e1rio declarou que entrou com um mandado de seguran\u00e7a para garantir seu\u00a0 direito, depois de ter esgotados todos os recursos com vistas a evitar sua decis\u00e3o de\u00a0 acionar a justi\u00e7a.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>O motorista da c\u00e2mara pediu aos vereadores presentes o empenho no sentido de interceder por ele junto a quem de direito para a solu\u00e7\u00e3o do problema. Marcus disse que lhe fora dito \u2013 ele n\u00e3o revelou por quem \u2013 que o curso de teologia \u201cn\u00e3o acrescenta nada \u00e0 sua fun\u00e7\u00e3o\u201d. O servidor revelou que ap\u00f3s fazer uma pesquisa junto aos legislativos das cidades de Coronel Fabriciano e Ipatinga, \u00a0descobriu que nestas casas o curso de teologia n\u00e3o sofre discrimina\u00e7\u00e3o como no legislativo de Tim\u00f3teo.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>\u201cN\u00e3o sou bajulador, Se depender disto to frito\u201d, disse Marcus a certa altura do seu pronunciamento, que seguiu uma linha de n\u00edtida decis\u00e3o de n\u00e3o agress\u00e3o. O funcion\u00e1rio invocou sua condi\u00e7\u00e3o de servidor comprometido com sua fun\u00e7\u00e3o para acrescentar raz\u00f5es \u00e0 sua indigna\u00e7\u00e3o por ter seu direito tolhido. \u201cSofro de injusti\u00e7a, relevante injusti\u00e7a, que a mim soa como covardia\u201d, desabafou Marcus Andr\u00e9. Ou\u00e7a o pronunciamento dele na \u00edntegra.<\/strong><\/p>\n<p><object width=\"580\" height=\"435\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"\/\/www.youtube.com\/v\/VtJUuLaCqDI?hl=pt_BR&amp;version=3&amp;rel=0\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed width=\"580\" height=\"435\" type=\"application\/x-shockwave-flash\" src=\"\/\/www.youtube.com\/v\/VtJUuLaCqDI?hl=pt_BR&amp;version=3&amp;rel=0\" allowFullScreen=\"true\" allowscriptaccess=\"always\" allowfullscreen=\"true\" \/><\/object><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Segundo o servidor a C\u00e2mara Municipal vem negando reconhecer seu curso de teologia para fins de progress\u00e3o. Marcus Andr\u00e9, funcion\u00e1rio concursado da C\u00e2mara Municipal de Tim\u00f3teo, ocupou a tribuna da casa na tarde desta segunda-feira(2) no expediente conhecido como Tribuna Livre, que faz parte da programa\u00e7\u00e3o das reuni\u00f5es ordin\u00e1rias do legislativo timotense. Com uma excelente [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts\/19373"}],"collection":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/comments?post=19373"}],"version-history":[{"count":0,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts\/19373\/revisions"}],"wp:attachment":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/media?parent=19373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/categories?post=19373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/tags?post=19373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}