{"id":19349,"date":"2014-06-06T00:46:11","date_gmt":"2014-06-06T03:46:11","guid":{"rendered":"http:\/\/portaldosilas.com.br\/?p=19349"},"modified":"2014-06-06T00:46:11","modified_gmt":"2014-06-06T03:46:11","slug":"escolha-um-competente-e-gente-da-gente-para-falar-em-sua-igreja","status":"publish","type":"post","link":"https:\/\/portaldosilas.com.br\/news\/2014\/06\/06\/escolha-um-competente-e-gente-da-gente-para-falar-em-sua-igreja\/","title":{"rendered":"Escolha um competente e gente da gente para falar em sua igreja&#8230;"},"content":{"rendered":"<figure id=\"attachment_19350\" aria-describedby=\"caption-attachment-19350\" style=\"width: 580px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2014\/06\/1546015_1385371455059776_125728919_n.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-19350 \" alt=\"1546015_1385371455059776_125728919_n\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2014\/06\/1546015_1385371455059776_125728919_n-580x477.jpg\" width=\"580\" height=\"477\" \/><\/a><figcaption id=\"caption-attachment-19350\" class=\"wp-caption-text\"><span style=\"color: #ffffff;\"><em><strong>Pastor e palestrante Irineu Felipe.<\/strong><\/em><\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>O Pr. Irineu Felipe, da Assembleia de Deus do\u00a0 bairro Limoeiro, em Tim\u00f3teo, vem se projetando pelas palestras que tem \u00a0ministrado em diversas congrega\u00e7\u00f5es do minist\u00e9rio Ad\u00e3o Ara\u00fajo. O tema preferido pelo Militar \u00e9 a fam\u00edlia, seguimento que lhe toca a alma e f\u00e1-lo destacado entre os que se preocupam com o assunto. Outros, por\u00e9m, t\u00eam ocupado a agenda do pastor que, com a mesma maestria, conhecimento de causa e profundidade, desenvolve com a evid\u00eancia de quem se dedica a fazer com perfei\u00e7\u00e3o aquilo a que se prop\u00f5e.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Pr. Irineu n\u00e3o \u00e9 daquele tipo de palestrante que todas as vezes\u00a0 que ministra repete o mesmo enfoque sobre o mesmo assunto. Seu conte\u00fado \u00e9 rico e, a partir disto, \u00e9 poss\u00edvel sempre ouvir Irineu falando a respeito de\u00a0 fam\u00edlia, por exemplo, sob prismas diversificados.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0Uma prova disto \u00e9 o acervo que o religioso tem e apresenta ao p\u00fablico interessado em ouvi-lo em suas igrejas. \u00a0Todas as ministra\u00e7\u00f5es s\u00e3o realizadas com o emprego de recurso audiovisual (Power Point) e v\u00eddeos.\u00a0<\/strong><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2014\/06\/Slide1-1-Copy.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-19351 aligncenter\" alt=\"Slide1 (1) (Copy)\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2014\/06\/Slide1-1-Copy-580x386.jpg\" width=\"580\" height=\"386\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2014\/06\/Slide3-Copy.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-19352 aligncenter\" alt=\"Slide3 (Copy)\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2014\/06\/Slide3-Copy-580x386.jpg\" width=\"580\" height=\"386\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2014\/06\/Slide4-Copy.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-19353 aligncenter\" alt=\"Slide4 (Copy)\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2014\/06\/Slide4-Copy-580x386.jpg\" width=\"580\" height=\"386\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2014\/06\/Slide5-Copy.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-19354 aligncenter\" alt=\"Slide5 (Copy)\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2014\/06\/Slide5-Copy-580x386.jpg\" width=\"580\" height=\"386\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2014\/06\/Slide6-Copy.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-19355 aligncenter\" alt=\"Slide6 (Copy)\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2014\/06\/Slide6-Copy-580x386.jpg\" width=\"580\" height=\"386\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2014\/06\/Slide7-Copy.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-19356 aligncenter\" alt=\"Slide7 (Copy)\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2014\/06\/Slide7-Copy-580x386.jpg\" width=\"580\" height=\"386\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2014\/06\/Slide8-Copy.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-19357 aligncenter\" alt=\"Slide8 (Copy)\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2014\/06\/Slide8-Copy-580x386.jpg\" width=\"580\" height=\"386\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2014\/06\/Slide9-Copy.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-19358 aligncenter\" alt=\"Slide9 (Copy)\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2014\/06\/Slide9-Copy-580x386.jpg\" width=\"580\" height=\"386\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2014\/06\/Slide10-Copy.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-19359 aligncenter\" alt=\"Slide10 (Copy)\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2014\/06\/Slide10-Copy-580x386.jpg\" width=\"580\" height=\"386\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2014\/06\/Slide11-Copy.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-19360 aligncenter\" alt=\"Slide11 (Copy)\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2014\/06\/Slide11-Copy-580x386.jpg\" width=\"580\" height=\"386\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2014\/06\/Slide12-Copy.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-19361 aligncenter\" alt=\"Slide12 (Copy)\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2014\/06\/Slide12-Copy-580x386.jpg\" width=\"580\" height=\"386\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2014\/06\/Slide13-Copy.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-19362 aligncenter\" alt=\"Slide13 (Copy)\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2014\/06\/Slide13-Copy-580x386.jpg\" width=\"580\" height=\"386\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2014\/06\/Slide14-Copy.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-19363 aligncenter\" alt=\"Slide14 (Copy)\" src=\"http:\/\/portaldosilas.com.br\/wp-content\/uploads\/2014\/06\/Slide14-Copy-580x386.jpg\" width=\"580\" height=\"386\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Pr. Irineu Felipe, da Assembleia de Deus do\u00a0 bairro Limoeiro, em Tim\u00f3teo, vem se projetando pelas palestras que tem \u00a0ministrado em diversas congrega\u00e7\u00f5es do minist\u00e9rio Ad\u00e3o Ara\u00fajo. O tema preferido pelo Militar \u00e9 a fam\u00edlia, seguimento que lhe toca a alma e f\u00e1-lo destacado entre os que se preocupam com o assunto. Outros, por\u00e9m, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts\/19349"}],"collection":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/comments?post=19349"}],"version-history":[{"count":0,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/posts\/19349\/revisions"}],"wp:attachment":[{"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/media?parent=19349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/categories?post=19349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portaldosilas.com.br\/news\/wp-json\/wp\/v2\/tags?post=19349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}